{"id":2331,"date":"2021-07-21T15:30:19","date_gmt":"2021-07-21T13:30:19","guid":{"rendered":"https:\/\/claai.info\/cms\/?p=2331"},"modified":"2021-07-21T15:31:04","modified_gmt":"2021-07-21T13:31:04","slug":"tutte-le-nuove-provvidenze-elba-wila-2021","status":"publish","type":"post","link":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/","title":{"rendered":"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021"},"content":{"rendered":"<p style=\"margin: 0cm; padding: 0px; text-align: justify;\">Ecco i nuovi accordi siglati dalle Confederazioni Artigiane &#8211; con la nostra C.L.A.A.I. &#8211; e dal Sindacato.<\/p>\n<p>Puoi scaricarli integralmente da questi link:<br \/>\n&#8211;\u00a0<a href=\"https:\/\/unioneartigiani.it\/app\/uploads\/2021\/07\/ACCORDO-PROVVIDENZE-2021.pdf\">Accordo Provvidenze 2021<\/a><br \/>\n&#8211;\u00a0<a href=\"https:\/\/unioneartigiani.it\/app\/uploads\/2021\/07\/Accordo-RLS-12.07.2021.pdf\">Accordo Formazione Sicurezza RLS<\/a><br \/>\n&#8211;\u00a0<a href=\"https:\/\/unioneartigiani.it\/app\/uploads\/2021\/07\/verbale-accordo-WILA-ELBA-12.07.2021-1-1.pdf\">Borse di Studio e Conferma Qualifica Apprendista da Wila a Elba<\/a><\/p>\n<p style=\"margin: 0cm; padding: 0px; font-family: Tahoma, Geneva, sans-serif; font-size: 12.09px; text-align: justify; overflow-wrap: break-word;\">Segnaliamo che nel verbale Provvidenze Elba sono state introdotte due nuove prestazioni a favore degli artigiani della Lombardia e pi\u00f9 precisamente\u00a0:<\/p>\n<ul style=\"margin-bottom: 0cm; font-family: Tahoma, Geneva, sans-serif; font-size: 12.09px;\">\n<li><strong>Imprenditoria femminile &#8211; Maternit\u00e0\u00a0<\/strong>riservato alle donne titolari di impresa artigiana in caso di nascita o adozione di un figlio per cui \u00e8 riconosciuto un contributo di \u20ac 500,00.<\/li>\n<\/ul>\n<ul style=\"margin-bottom: 0cm; font-family: Tahoma, Geneva, sans-serif; font-size: 12.09px;\">\n<li><strong>Imprenditoria femminile &#8211; incremento occupazionale ( IFO )\u00a0<\/strong>riservato alle imprese femminili (ditte individuali il cui titolare \u00e8 donna; societ\u00e0 di persone in cui almeno il 60% sono donne; societ\u00e0 di capitali, se almeno i 2\/3 delle quote sono sottoscritte da donne e se l&#8217;amministrazione \u00e8 formata per 1\/3 almeno di donne) che abbiamo assunto nel corso del 2021 un lavoratore a tempo indeterminato o tempo determinato di almeno 12 mesi, che incrementi il numero di lavoratori gi\u00e0 in forza per almeno 4 mesi ; il contributo riconosciuto \u00e8 ari ad \u20ac 500,00.<\/li>\n<li>Si rammenta altres\u00ec le decorrenze indicate nel primo capoverso dell&#8217;accordo qui allegato.\u00a0<strong>Le domande delle provvidenze relative ai primi sette mesi dell&#8217;anno 2021 dovranno essere presentate ad ELBA entro il 31 ottobre 2021.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0cm; padding: 0px; font-size: 11pt; font-family: Calibri, sans-serif; overflow-wrap: break-word;\">Per info, chiarimenti e appuntamenti<br \/>\nufficio.sindacale@unioneservizi.it<br \/>\n02 8375941<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco i nuovi accordi siglati dalle Confederazioni Artigiane &#8211; con la nostra C.L.A.A.I. &#8211; e dal Sindacato. Puoi scaricarli integralmente da questi link: &#8211;\u00a0Accordo Provvidenze 2021 &#8211;\u00a0Accordo Formazione Sicurezza RLS &#8211;\u00a0Borse di Studio e Conferma Qualifica Apprendista da Wila a Elba Segnaliamo che nel verbale Provvidenze Elba sono state introdotte due nuove prestazioni a favore [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8,1,12],"tags":[],"class_list":["post-2331","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","category-senza-categoria","category-sindacale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021 - claai.info<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021 - claai.info\" \/>\n<meta property=\"og:description\" content=\"Ecco i nuovi accordi siglati dalle Confederazioni Artigiane &#8211; con la nostra C.L.A.A.I. &#8211; e dal Sindacato. Puoi scaricarli integralmente da questi link: &#8211;\u00a0Accordo Provvidenze 2021 &#8211;\u00a0Accordo Formazione Sicurezza RLS &#8211;\u00a0Borse di Studio e Conferma Qualifica Apprendista da Wila a Elba Segnaliamo che nel verbale Provvidenze Elba sono state introdotte due nuove prestazioni a favore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"claai.info\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-21T13:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T13:31:04+00:00\" \/>\n<meta name=\"author\" content=\"Roldano Radaelli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roldano Radaelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/\"},\"author\":{\"name\":\"Roldano Radaelli\",\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/#\\\/schema\\\/person\\\/d634d034d50532073c4c85c3eb23b46e\"},\"headline\":\"TUTTE LE NUOVE PROVVIDENZE ELBA\\\/WILA 2021\",\"datePublished\":\"2021-07-21T13:30:19+00:00\",\"dateModified\":\"2021-07-21T13:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/\"},\"wordCount\":222,\"articleSection\":{\"0\":\"Comunicati Stampa\",\"2\":\"Sindacale\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/\",\"url\":\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/\",\"name\":\"TUTTE LE NUOVE PROVVIDENZE ELBA\\\/WILA 2021 - claai.info\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/#website\"},\"datePublished\":\"2021-07-21T13:30:19+00:00\",\"dateModified\":\"2021-07-21T13:31:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/#\\\/schema\\\/person\\\/d634d034d50532073c4c85c3eb23b46e\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/claai.info\\\/cms\\\/tutte-le-nuove-provvidenze-elba-wila-2021\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/claai.info\\\/cms\\\/\",\"name\":\"claai.info\",\"description\":\"Confederazione delle Libere Associazioni Artigiane Italiane\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/claai.info\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/claai.info\\\/cms\\\/#\\\/schema\\\/person\\\/d634d034d50532073c4c85c3eb23b46e\",\"name\":\"Roldano Radaelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g\",\"caption\":\"Roldano Radaelli\"},\"url\":\"https:\\\/\\\/claai.info\\\/cms\\\/author\\\/rradaelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021 - claai.info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/","og_locale":"it_IT","og_type":"article","og_title":"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021 - claai.info","og_description":"Ecco i nuovi accordi siglati dalle Confederazioni Artigiane &#8211; con la nostra C.L.A.A.I. &#8211; e dal Sindacato. Puoi scaricarli integralmente da questi link: &#8211;\u00a0Accordo Provvidenze 2021 &#8211;\u00a0Accordo Formazione Sicurezza RLS &#8211;\u00a0Borse di Studio e Conferma Qualifica Apprendista da Wila a Elba Segnaliamo che nel verbale Provvidenze Elba sono state introdotte due nuove prestazioni a favore [&hellip;]","og_url":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/","og_site_name":"claai.info","article_published_time":"2021-07-21T13:30:19+00:00","article_modified_time":"2021-07-21T13:31:04+00:00","author":"Roldano Radaelli","twitter_misc":{"Scritto da":"Roldano Radaelli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/#article","isPartOf":{"@id":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/"},"author":{"name":"Roldano Radaelli","@id":"https:\/\/claai.info\/cms\/#\/schema\/person\/d634d034d50532073c4c85c3eb23b46e"},"headline":"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021","datePublished":"2021-07-21T13:30:19+00:00","dateModified":"2021-07-21T13:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/"},"wordCount":222,"articleSection":{"0":"Comunicati Stampa","2":"Sindacale"},"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/","url":"https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/","name":"TUTTE LE NUOVE PROVVIDENZE ELBA\/WILA 2021 - claai.info","isPartOf":{"@id":"https:\/\/claai.info\/cms\/#website"},"datePublished":"2021-07-21T13:30:19+00:00","dateModified":"2021-07-21T13:31:04+00:00","author":{"@id":"https:\/\/claai.info\/cms\/#\/schema\/person\/d634d034d50532073c4c85c3eb23b46e"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/claai.info\/cms\/tutte-le-nuove-provvidenze-elba-wila-2021\/"]}]},{"@type":"WebSite","@id":"https:\/\/claai.info\/cms\/#website","url":"https:\/\/claai.info\/cms\/","name":"claai.info","description":"Confederazione delle Libere Associazioni Artigiane Italiane","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/claai.info\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/claai.info\/cms\/#\/schema\/person\/d634d034d50532073c4c85c3eb23b46e","name":"Roldano Radaelli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97809b9ddd3df37c1ba1778903f83cd304e9ead5255b24490d0157d2cf5c0bac?s=96&d=mm&r=g","caption":"Roldano Radaelli"},"url":"https:\/\/claai.info\/cms\/author\/rradaelli\/"}]}},"_links":{"self":[{"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/posts\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":2,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"predecessor-version":[{"id":2334,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/posts\/2331\/revisions\/2334"}],"wp:attachment":[{"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/claai.info\/cms\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}